{"id":11625,"date":"2023-05-18T15:30:40","date_gmt":"2023-05-18T13:30:40","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=6879"},"modified":"2023-07-12T18:36:16","modified_gmt":"2023-07-12T16:36:16","slug":"cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/","title":{"rendered":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas"},"content":{"rendered":"<p>El presidente de COCEMFE Val\u00e8ncia <strong>Pascual Castell\u00f3<\/strong> y el Director de <strong>Adams Formaci\u00f3n Val\u00e8ncia, Salvador Penad\u00e9s<\/strong>, han firmado un nuevo <strong>Convenio de colaboraci\u00f3n<\/strong> entre ambas entidades ampliando los beneficios para las personas asociadas a las entidades que integran COCEMFE Val\u00e8ncia.<\/p>\n<p><strong>Adams<\/strong> es un centro de <strong>formaci\u00f3n referente en Valencia<\/strong>, especializados en la preparaci\u00f3n para <strong>oposiciones del sector p\u00fablico,<\/strong> tanto presencial, como online y formaci\u00f3n para personas desempleadas. Pascual Castell\u00f3 destaca la necesidad de acercar el Empleo P\u00fablico a nuestro colectivo, como una v\u00eda m\u00e1s de acceso a puestos de trabajo.<\/p>\n<p>Dentro del convenio se encuentran, por ejemplo,<strong> descuentos tanto en la matr\u00edcula como en el material<\/strong> necesario para la preparaci\u00f3n de oposiciones. Concretamente, Adams Formaci\u00f3n, ofrece <strong>3 becas anuales<\/strong> a personas usuarias o asociadas que est\u00e9n interesadas en opositar. Por otro lado, tambi\u00e9n se ofrece\u00a0un <strong>servicio de asesoramiento<\/strong> especializado, as\u00ed como una <strong>oferta de formaci\u00f3n<\/strong> amplia para la mejora de la empleabilidad del colectivo. Adem\u00e1s, y como ampliaci\u00f3n al convenio firmado en el a\u00f1o 2019, cursos de formaci\u00f3n subvencionados a las personas usuarias (pertenecientes a colectivos prioritarios) as\u00ed como familiares de estos y a trabajadores de COCEMFE Valencia y sus entidades federadas.<\/p>\n<p>Otro punto importante del convenio, es el compromiso por parte de la empresa de apostar por la<strong> contrataci\u00f3n de personas con certificado de discapacidad<\/strong>. En las pr\u00f3ximas semanas se realizar\u00e1 una campa\u00f1a de difusi\u00f3n por parte de COCEMFE Val\u00e8ncia para hacer llegar toda la informaci\u00f3n necesaria a las asociaciones de c\u00f3mo poder acceder a las ventajas firmadas por ambas entidades.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Si quieres conocer todos las formaciones disponibles, haz click en el siguiente enlace:<\/strong> <a href=\"https:\/\/www.adams.es\/site\/asociados-cocemfe\/\">https:\/\/www.adams.es\/site\/asociados-cocemfe\/<\/a><\/li>\n<\/ul>\n<p>Visitas: 23<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de COCEMFE Val\u00e8ncia Pascual Castell\u00f3 y el Director de Adams Formaci\u00f3n Val\u00e8ncia, Salvador Penad\u00e9s, han firmado un nuevo Convenio de colaboraci\u00f3n entre ambas entidades ampliando los beneficios para las personas asociadas a las entidades que integran COCEMFE Val\u00e8ncia. Adams es un centro de formaci\u00f3n referente en Valencia, especializados en la preparaci\u00f3n para oposiciones&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":6880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[280,124,281,211,282,148,149,283,284],"class_list":["post-11625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-cocemfe-valencia","tag-adams-formacion","tag-cocemfe-valencia-val","tag-contratacion","tag-convenio-val","tag-convenios","tag-discapacidad-val","tag-empleo-val","tag-formacion","tag-oposiciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"El presidente de COCEMFE Val\u00e8ncia Pascual Castell\u00f3 y el Director de Adams Formaci\u00f3n Val\u00e8ncia, Salvador Penad\u00e9s, han firmado un nuevo Convenio de colaboraci\u00f3n entre ambas entidades ampliando los beneficios para las personas asociadas a las entidades que integran COCEMFE Val\u00e8ncia. Adams es un centro de formaci\u00f3n referente en Valencia, especializados en la preparaci\u00f3n para oposiciones&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T13:30:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-12T16:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas\",\"datePublished\":\"2023-05-18T13:30:40+00:00\",\"dateModified\":\"2023-07-12T16:36:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg\",\"keywords\":[\"ADAMS FORMACI\u00d3N\",\"COCEMFE Valencia\",\"contrataci\u00f3n\",\"CONVENIO\",\"CONVENIOS\",\"discapacidad\",\"empleo\",\"Formaci\u00f3n\",\"oposiciones\"],\"articleSection\":[\"Art\u00edculos COCEMFE Valencia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/\",\"name\":\"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg\",\"datePublished\":\"2023-05-18T13:30:40+00:00\",\"dateModified\":\"2023-07-12T16:36:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/","og_locale":"es_ES","og_type":"article","og_title":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia","og_description":"El presidente de COCEMFE Val\u00e8ncia Pascual Castell\u00f3 y el Director de Adams Formaci\u00f3n Val\u00e8ncia, Salvador Penad\u00e9s, han firmado un nuevo Convenio de colaboraci\u00f3n entre ambas entidades ampliando los beneficios para las personas asociadas a las entidades que integran COCEMFE Val\u00e8ncia. Adams es un centro de formaci\u00f3n referente en Valencia, especializados en la preparaci\u00f3n para oposiciones&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas","og_url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2023-05-18T13:30:40+00:00","article_modified_time":"2023-07-12T16:36:16+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg","type":"image\/jpeg"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas","datePublished":"2023-05-18T13:30:40+00:00","dateModified":"2023-07-12T16:36:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/"},"wordCount":320,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg","keywords":["ADAMS FORMACI\u00d3N","COCEMFE Valencia","contrataci\u00f3n","CONVENIO","CONVENIOS","discapacidad","empleo","Formaci\u00f3n","oposiciones"],"articleSection":["Art\u00edculos COCEMFE Valencia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/","url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/","name":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg","datePublished":"2023-05-18T13:30:40+00:00","dateModified":"2023-07-12T16:36:16+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-17-at-10.41.03-Mayte-Tarrega.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-y-adams-formacion-valencia-firman-un-nuevo-convenio-que-amplia-los-beneficios-para-personas-asociadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"COCEMFE Val\u00e8ncia y Adams Formaci\u00f3n firman un nuevo convenio que ampl\u00eda los beneficios para personas asociadas"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=11625"}],"version-history":[{"count":3,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11625\/revisions"}],"predecessor-version":[{"id":11739,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11625\/revisions\/11739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/6880"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=11625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=11625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=11625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}