{"id":11626,"date":"2023-05-30T10:12:32","date_gmt":"2023-05-30T08:12:32","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=6885"},"modified":"2023-09-21T10:53:32","modified_gmt":"2023-09-21T08:53:32","slug":"cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/","title":{"rendered":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>El nuevo equipo apuesta por una l\u00ednea continuista y el fortalecimiento de los v\u00ednculos con las asociaciones<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">El pasado s\u00e1bado 27 de mayo, la Federaci\u00f3 d&#8217;Associacions de Persones amb Discapacitat F\u00edsica i Org\u00e0nica de la Prov\u00edncia de Val\u00e8ncia (<\/span><b>COCEMFE Val\u00e8ncia<\/b><span style=\"font-weight: 400;\">) renov\u00f3 su junta directiva tras una asamblea electoral que situ\u00f3 a <\/span><b>Maria Jos\u00e9 Mart\u00ednez Casamayor<\/b><span style=\"font-weight: 400;\"> como nueva <\/span><b>presidenta de la entidad<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Confederaci\u00f3n, que agrupa un total de <\/span><b>43 asociaciones dedicadas a la discapacidad f\u00edsica y org\u00e1nica en la provincia de Val\u00e8ncia<\/b><span style=\"font-weight: 400;\">, inicia as\u00ed una etapa marcada, seg\u00fan palabras de Mart\u00ednez Casamayor, por la <\/span><b>\u201ccontinuidad\u201d<\/b><span style=\"font-weight: 400;\"> con el planteamiento y acciones ya iniciadas durante la legislatura anterior, pero con <\/span><b>\u201cilusiones renovadas\u201d<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre las principales l\u00edneas de trabajo a desarrollar se encuentra la necesidad de potenciar, por un lado, las <\/span><b>relaciones entre las diferentes asociaciones<\/b><span style=\"font-weight: 400;\"> y, por otro lado, los v<\/span><b>\u00ednculos de estas con COCEMFE Val\u00e8ncia<\/b><span style=\"font-weight: 400;\">, una petici\u00f3n recogida en el Consell Provincial celebrado en el mes de febrero. Para ello, el nuevo equipo directivo trabajar\u00e1 por el establecimiento de una <\/span><b>jornada l\u00fadica<\/b><span style=\"font-weight: 400;\"> dirigida a estrechar lazos entre las asociaciones, la recuperaci\u00f3n del 3 de diciembre,<\/span><b> D\u00eda Internacional de las Personas con Discapacidad<\/b><span style=\"font-weight: 400;\">, como una fecha de reivindicaci\u00f3n y unidad, o el afianzamiento de los proyectos culturales <\/span><b>\u2018Descobrim\u2019 y \u2018Sense Barreres\u2019<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La adaptaci\u00f3n a nuevas aplicaciones de <\/span><b>bases de datos<\/b><span style=\"font-weight: 400;\"> o el mantenimiento del grado de <\/span><b>transparencia<\/b><span style=\"font-weight: 400;\"> actual de todos los proyectos y acciones que se realizan, ser\u00e1n tambi\u00e9n puntos importantes para la nueva junta directiva que centrar\u00e1 esfuerzos en favorecer la integraci\u00f3n<\/span><b> de los y las j\u00f3venes en el mundo asociativo<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La nueva junta directiva estar\u00e1 conformada por un total de siete miembros: <\/span><b>Maria Jos\u00e9 Mart\u00ednez Casamayor<\/b><span style=\"font-weight: 400;\"> (APIP CV) en el cargo de presidenta, <\/span><b>Silvia S\u00e1nchez Bos\u00f3<\/b><span style=\"font-weight: 400;\"> (TDI) y <\/span><b>Ricardo Gim\u00e9nez Monter<\/b><span style=\"font-weight: 400;\"> (QUSIBA), como vicepresidenta primera y vicepresidente segundo, respectivamente, <\/span><b>Pascual Castell\u00f3 Bellver<\/b><span style=\"font-weight: 400;\"> (AETHCV) como secretario, <\/span><b>Albert Mar\u00ed Sanchis<\/b><span style=\"font-weight: 400;\"> (AVCOM CV) en el cargo de tesorero y, por \u00faltimo, <strong>Juan Mondejar S\u00e1nchez<\/strong> (ADAI CV) y <strong>Magdalena Michavila Mart\u00ed<\/strong> (AFIVAN) como vocales.<\/span><\/p>\n<p>Visitas: 74<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; El nuevo equipo apuesta por una l\u00ednea continuista y el fortalecimiento de los v\u00ednculos con las asociaciones &nbsp; El pasado s\u00e1bado 27 de mayo, la Federaci\u00f3 d&#8217;Associacions de Persones amb Discapacitat F\u00edsica i Org\u00e0nica de la Prov\u00edncia de Val\u00e8ncia (COCEMFE Val\u00e8ncia) renov\u00f3 su junta directiva tras una asamblea electoral que situ\u00f3 a Maria Jos\u00e9&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":11556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[285,146,286,287,288,289,290,195,291],"class_list":["post-11626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-cocemfe-valencia","tag-asamblea-electoral","tag-cultura-val","tag-descobrim","tag-elecciones","tag-junta-directiva","tag-juventud","tag-presidencia","tag-sense-barreres-val","tag-transparencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"&nbsp; El nuevo equipo apuesta por una l\u00ednea continuista y el fortalecimiento de los v\u00ednculos con las asociaciones &nbsp; El pasado s\u00e1bado 27 de mayo, la Federaci\u00f3 d&#8217;Associacions de Persones amb Discapacitat F\u00edsica i Org\u00e0nica de la Prov\u00edncia de Val\u00e8ncia (COCEMFE Val\u00e8ncia) renov\u00f3 su junta directiva tras una asamblea electoral que situ\u00f3 a Maria Jos\u00e9&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T08:12:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T08:53:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1309\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta\",\"datePublished\":\"2023-05-30T08:12:32+00:00\",\"dateModified\":\"2023-09-21T08:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg\",\"keywords\":[\"Asamblea Electoral\",\"cultura\",\"Descobrim\",\"Elecciones\",\"Junta directiva\",\"juventud\",\"Presidencia\",\"sense barreres\",\"Transparencia\"],\"articleSection\":[\"Art\u00edculos COCEMFE Valencia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/\",\"name\":\"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg\",\"datePublished\":\"2023-05-30T08:12:32+00:00\",\"dateModified\":\"2023-09-21T08:53:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg\",\"width\":1309,\"height\":969},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/","og_locale":"es_ES","og_type":"article","og_title":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia","og_description":"&nbsp; El nuevo equipo apuesta por una l\u00ednea continuista y el fortalecimiento de los v\u00ednculos con las asociaciones &nbsp; El pasado s\u00e1bado 27 de mayo, la Federaci\u00f3 d&#8217;Associacions de Persones amb Discapacitat F\u00edsica i Org\u00e0nica de la Prov\u00edncia de Val\u00e8ncia (COCEMFE Val\u00e8ncia) renov\u00f3 su junta directiva tras una asamblea electoral que situ\u00f3 a Maria Jos\u00e9&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta","og_url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2023-05-30T08:12:32+00:00","article_modified_time":"2023-09-21T08:53:32+00:00","og_image":[{"width":1309,"height":969,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg","type":"image\/jpeg"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta","datePublished":"2023-05-30T08:12:32+00:00","dateModified":"2023-09-21T08:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/"},"wordCount":376,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg","keywords":["Asamblea Electoral","cultura","Descobrim","Elecciones","Junta directiva","juventud","Presidencia","sense barreres","Transparencia"],"articleSection":["Art\u00edculos COCEMFE Valencia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/","url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/","name":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg","datePublished":"2023-05-30T08:12:32+00:00","dateModified":"2023-09-21T08:53:32+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/05\/Propuesta-de-candidatura-2023-1-copia_page-0001.jpg","width":1309,"height":969},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-renueva-su-junta-directiva-con-maria-jose-martinez-casamayor-como-nueva-presidenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"COCEMFE Val\u00e8ncia renueva su junta directiva con Maria Jos\u00e9 Mart\u00ednez Casamayor como presidenta"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=11626"}],"version-history":[{"count":2,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11626\/revisions"}],"predecessor-version":[{"id":12227,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/11626\/revisions\/12227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/11556"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=11626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=11626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=11626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}