{"id":12113,"date":"2023-09-12T10:03:11","date_gmt":"2023-09-12T08:03:11","guid":{"rendered":"https:\/\/cocemfevalencia.org\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/"},"modified":"2023-09-14T17:04:36","modified_gmt":"2023-09-14T15:04:36","slug":"la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/","title":{"rendered":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre"},"content":{"rendered":"<p><b>NdP COMUNICADO de la COMISI\u00d3N de SANIDAD de COCEMFE-VALENCIA (CSdCV) 05\/09\/2023<\/b><\/p>\n<p>Realizada la OCTAVA reuni\u00f3n del a\u00f1o, entidades como <b>ACVEM<\/b> (Asociaci\u00f3n de la Comunidad Valenciana de Esclerosis M\u00faltiple), <b>AFIVAN<\/b> (Asociaci\u00f3n de Fibromialgia de Valencia Norte), <b>ALCER-Turia<\/b> (Asociaci\u00f3n para la Lucha Contra las Enfermedades del Ri\u00f1\u00f3n en Valencia),<b> ASIDIT<\/b> (Aociaci\u00f3n de Torrent por la Integraci\u00f3n Social de personas con Diversidad funcional), <b>AVATCOR<\/b> (Asociaci\u00f3n Valenciana de Trasplantados de CORaz\u00f3n y Pulm\u00f3n), <b>CODOFIVA<\/b> (COordinadora de DIsminuidos FIsicos de VAlencia, <b>PARKINSON-GAND\u00cdA<\/b> (Asociaci\u00f3n de Personas afectadas por el Parkinson de la Safor), y <b>AXEM-\u00c1REA 13<\/b> (Asociaci\u00f3n de X\u00e0tiva contra la Esclerosis M\u00faltiple del \u00c1REA 13) entre otras asociaciones, participaron activamente para evaluar y optimar el sistema socio-sanitario de la provincia de Valencia y por defecto, de la Comunidad Valencia.<\/p>\n<p>La <b>COMISI\u00d3N DE SANIDAD<\/b> realiz\u00f3 su REUNI\u00d3N mensual el pasado <b>05<\/b> de <b>SEPTIEMBRE<\/b><span class=\"Apple-converted-space\">\u00a0 <\/span>del <b>2023<\/b> por VIDEO CONFERENCIA (MEET de la CSdCV) y esta es su <b>NOTA de PRENSA.<\/b><\/p>\n<p>Se comenz\u00f3 la 8\u00aa reuni\u00f3n del a\u00f1o (primera despu\u00e9s del periodo vacacional) y al igual que en los meses anteriores, se realiz\u00f3 por VideoConferencia, principalmente por motivos de seguridad y comodidad. Se utiliza la plataforma MEET (Cuenta de Google creada para la Comisi\u00f3n de Sanidad por Cocemfe Valencia) y da comienzo el encuentro, despu\u00e9s de los saludos de rigor, siendo las 10:05 de la ma\u00f1ana.<\/p>\n<p>Se comenz\u00f3 retomando el tema pand\u00e9mico, ya que se constata el aumento de casos. Se habla de m\u00e1s de un 21% y que en algunos Hospitales de Valencia, se vuelve a recomendar el uso de mascarillas. Las personas participantes tienen claro que la situaci\u00f3n es tratada como \u201cGripal\u201d, pese a que las personas vacunadas siguen contagi\u00e1ndose de Covid-19 y en algunos casos de manera m\u00e1s virulenta aunque de menor convalecencia. Comienzan a surgir dudas razonables sobre los efectos secundarios de las vacunas, aun as\u00ed, y pese a que mucha gente solamente se ha puesto las dos primeras dosis, se sigue recomendando la vacunaci\u00f3n como mejor barrera de contagio.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Por otro lado se comentan diferentes situaciones respecto del tema Pand\u00e9mico, como son las NO BAJAS por Covid-19 y la escasez de atenci\u00f3n por Covid-persistente. Lo mismo sucede con la situaci\u00f3n despu\u00e9s de pandemia; citas previas, nula o escasa atenci\u00f3n telef\u00f3nica, listas de espera,,, Situaci\u00f3n que contin\u00faa molestando seriamente a la poblaci\u00f3n en general.<\/p>\n<p>Se comenta la reuni\u00f3n mantenida por el representante de la CSdCV. Sr. Ram\u00f3n Villora, en la Comisi\u00f3n de adjudicaci\u00f3n de Sillas de Ruedas El\u00e9ctricas de la Conseller\u00eda de Sanitat. En el mes de Julio se sentaron bases y acuerdos a la hora de solicitar o renovar una silla de ruedas el\u00e9ctrica y en este mes se ratificar\u00e1n decisiones concretas. En la reuni\u00f3n de Octubre se explicara detalladamente como ha de ser exacto este proceso. Por otra parte, se resalt\u00f3 la gran labor de las personas representantes y participantes en dicha comisi\u00f3n, ya que meses atr\u00e1s se hab\u00edan tomado unas directrices nada adecuados con la realidad y que perjudicaban seriamente a las personas usuarias de sistemas el\u00e9ctricos para su movilidad y al propio sistema de salud Valenciano. Por el tema vacacional, no se han realizado mas intervenciones.<\/p>\n<p>Se realiz\u00f3 una pausa en la reuni\u00f3n, siendo las 10:55 de la ma\u00f1ana para realizar la captura de pantalla de este mes, para adjuntarla con la NdP de la CSdCV.<\/p>\n<p>Tambi\u00e9n se informa a los presentes que a\u00fan quedan cambios pol\u00edticos, de direcciones y secretar\u00edas por confirmar, tras las \u00faltimas elecciones auton\u00f3micas, por lo que se acuerda, una vez designados y tomado posesi\u00f3n de sus respectivos cargo, solicitar cuanto antes reuniones para explicar la situaci\u00f3n y reclamar una mejora en la atenci\u00f3n sanitaria. Igualmente se comenta la elaboraci\u00f3n de la campa\u00f1a que se pretende realizar desde la CSdCV para la difusi\u00f3n e informaci\u00f3n de las Hojas de reclamaciones-sugerencias-agradecimiento, que existe o han de existir en los centros sanitarios de la Comunidad Valenciana.<\/p>\n<p>Por otro lado se informa a las entidades para que realicen \u201cpreguntas\u201d para un peritaje en materia de accesibilidad y adaptabilidad de los Centros Sanitarios, consultas, \u00e1reas de atenci\u00f3n, etc. en los diferentes centros sanitarios. Se realizar\u00e1 un escrito desde la CSdCV, a todas las entidades federadas, para que por medio de sus usuarios y a trav\u00e9s de un formulario est\u00e1ndar que se elaborar\u00e1 con estos \u201cItems\u201d, nos hagan llegar las deficiencias y la falta de accesibilidad o adaptabilidad en los diferentes centros sanitarios de la provincia de valencia.<\/p>\n<p>Por otra parte, se est\u00e1 realizando un \u201cdec\u00e1logo\u201d a modo de resumen, de los cuidados esenciales que las PcD necesitan en los centros sanitarios. Se elaborar\u00e1 un documento de igual manera que el anterior y se pondr\u00e1 en com\u00fan al resto de entidades para su valoraci\u00f3n.<\/p>\n<p>Referente a la designaci\u00f3n de cargos y representaciones de la comisi\u00f3n de trabajo, se ratific\u00f3 que la Secretaria de la comisi\u00f3n sea la Sra. M\u00aa del Carmen Domingo Alvaro y la Coordiaci\u00f3n de la comisi\u00f3n siga recayendo en el Sr. Ezequiel Ruiz S\u00e1nchez, representantes ambos de AFIVAN (Asociaci\u00f3n Fibromialgia de Valencia Norte) y AXEM-\u00c1REA 13 (Asociaci\u00f3n de X\u00e0tiva contra la Esclerosis M\u00faltiple del \u00e1rea 13) respectivamente.<\/p>\n<p>De igual modo, se ratific\u00f3 tambi\u00e9n designar al Sr. Jos\u00e9 Ojeda Calero como representante de la CSdCV. en la Comisi\u00f3n de Sanidad del CERMI-CV y al Sr. Ram\u00f3n Villora Villa como representante de la CSdCV en la Comisi\u00f3n de adjudicaciones de Sillas de Ruedas El\u00e9ctricas de la Conseller\u00eda de Sanidad de la Generalitat Valenciana. Ambos representantes de APiP-CV (Asociaci\u00f3n de Polio y s\u00edndrome Post Polio de la Comunidad Valenciana) y AXEM-\u00c1REA 13 (Asociaci\u00f3n de X\u00e0tiva contra la Esclerosis M\u00faltiple del \u00e1rea 13) respectivamente.<\/p>\n<p>En caso de no poder asistir el Sr. Ram\u00f3n Villora, se designa al Sr, Ezequiel Ruiz, como sustituto en la comisi\u00f3n, ya que as\u00ed se decidi\u00f3 en la formalizaci\u00f3n de la Comisi\u00f3n de Silla de Ruedas El\u00e9ctricas.<\/p>\n<p>Como relaciones p\u00fablicas de la CSdCV, queda designado el Sr. D. Salvador Pastor, representante de AVATCOR (Asociaci\u00f3n Valenciana de Trasplantados de Coraz\u00f3n y Pulm\u00f3n).<\/p>\n<p>A todos los asistentes, se les comunica la URGENTE y NECESARIA ACTUALIZACI\u00d3N de datos y de documentaci\u00f3n, tanto de la Ley de Protecci\u00f3n de datos (LPdD) como de Voluntariado de Cocemfe Valencia. Se aprueba volver a remitir a las entidades que no est\u00e9n actualizadas toda la documentaci\u00f3n, ya que de NO ponerse al d\u00eda, NO podr\u00e1n participar en las reuniones de la CSdCV.<\/p>\n<p>Se llega a las 11:50h. de la ma\u00f1ana y no habiendo preguntas, no saliendo mas temas importantes a tratar o por desarrollar, ya que se han comentado por Whatsapp y en RRSS, se da por finalizada esta 8\u00aa reuni\u00f3n del a\u00f1o 2023, no sin antes desearnos un estupendo mes.<\/p>\n<p>Este es la NdP de la CSdCV realizado conjuntamente por:<\/p>\n<p>Sra. M\u00aa del Carmen Domingo y Sr. Ezequiel Ruiz;<\/p>\n<p>Secretaria y Coordinador de la CSdCV, y miembros de AFIVAN y AXEM-\u00e1rea 13,\u00a0respectivamente.<\/p>\n<p>Visitas: 3<\/p>","protected":false},"excerpt":{"rendered":"<p>NdP COMUNICADO de la COMISI\u00d3N de SANIDAD de COCEMFE-VALENCIA (CSdCV) 05\/09\/2023 Realizada la OCTAVA reuni\u00f3n del a\u00f1o, entidades como ACVEM (Asociaci\u00f3n de la Comunidad Valenciana de Esclerosis M\u00faltiple), AFIVAN (Asociaci\u00f3n de Fibromialgia de Valencia Norte), ALCER-Turia (Asociaci\u00f3n para la Lucha Contra las Enfermedades del Ri\u00f1\u00f3n en Valencia), ASIDIT (Aociaci\u00f3n de Torrent por la Integraci\u00f3n Social&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[263],"tags":[368],"class_list":["post-12113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-cocemfe-valencia-es","tag-comision-de-sanidad-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"NdP COMUNICADO de la COMISI\u00d3N de SANIDAD de COCEMFE-VALENCIA (CSdCV) 05\/09\/2023 Realizada la OCTAVA reuni\u00f3n del a\u00f1o, entidades como ACVEM (Asociaci\u00f3n de la Comunidad Valenciana de Esclerosis M\u00faltiple), AFIVAN (Asociaci\u00f3n de Fibromialgia de Valencia Norte), ALCER-Turia (Asociaci\u00f3n para la Lucha Contra las Enfermedades del Ri\u00f1\u00f3n en Valencia), ASIDIT (Aociaci\u00f3n de Torrent por la Integraci\u00f3n Social&hellip;&nbsp;Leer m\u00e1s &raquo;La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-12T08:03:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T15:04:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/\"},\"author\":{\"name\":\"comunicacio\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/84dc42180efe17bdafa0a7a8702d24c8\"},\"headline\":\"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre\",\"datePublished\":\"2023-09-12T08:03:11+00:00\",\"dateModified\":\"2023-09-14T15:04:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/\"},\"wordCount\":1246,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png\",\"keywords\":[\"COMISI\u00d3N DE SANIDAD\"],\"articleSection\":[\"Art\u00edculos COCEMFE Valencia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/\",\"name\":\"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png\",\"datePublished\":\"2023-09-12T08:03:11+00:00\",\"dateModified\":\"2023-09-14T15:04:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png\",\"width\":1150,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/84dc42180efe17bdafa0a7a8702d24c8\",\"name\":\"comunicacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"caption\":\"comunicacio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/","og_locale":"es_ES","og_type":"article","og_title":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia","og_description":"NdP COMUNICADO de la COMISI\u00d3N de SANIDAD de COCEMFE-VALENCIA (CSdCV) 05\/09\/2023 Realizada la OCTAVA reuni\u00f3n del a\u00f1o, entidades como ACVEM (Asociaci\u00f3n de la Comunidad Valenciana de Esclerosis M\u00faltiple), AFIVAN (Asociaci\u00f3n de Fibromialgia de Valencia Norte), ALCER-Turia (Asociaci\u00f3n para la Lucha Contra las Enfermedades del Ri\u00f1\u00f3n en Valencia), ASIDIT (Aociaci\u00f3n de Torrent por la Integraci\u00f3n Social&hellip;&nbsp;Leer m\u00e1s &raquo;La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre","og_url":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2023-09-12T08:03:11+00:00","article_modified_time":"2023-09-14T15:04:36+00:00","og_image":[{"width":1150,"height":576,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png","type":"image\/png"}],"author":"comunicacio","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"comunicacio","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/"},"author":{"name":"comunicacio","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/84dc42180efe17bdafa0a7a8702d24c8"},"headline":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre","datePublished":"2023-09-12T08:03:11+00:00","dateModified":"2023-09-14T15:04:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/"},"wordCount":1246,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png","keywords":["COMISI\u00d3N DE SANIDAD"],"articleSection":["Art\u00edculos COCEMFE Valencia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/","url":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/","name":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png","datePublished":"2023-09-12T08:03:11+00:00","dateModified":"2023-09-14T15:04:36+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/09\/Captura-de-pantalla-2023-09-12-a-las-9.59.53.png","width":1150,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/la-comision-de-sanidad-de-cocemfe-valencia-realiza-su-reunion-del-mes-de-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"La Comisi\u00f3n de Sanidad de COCEMFE Valencia realiza su reuni\u00f3n del mes de septiembre"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/84dc42180efe17bdafa0a7a8702d24c8","name":"comunicacio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","caption":"comunicacio"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/12113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=12113"}],"version-history":[{"count":2,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/12113\/revisions"}],"predecessor-version":[{"id":12167,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/12113\/revisions\/12167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/12111"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=12113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=12113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=12113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}