{"id":14929,"date":"2024-11-08T13:02:09","date_gmt":"2024-11-08T12:02:09","guid":{"rendered":"https:\/\/cocemfevalencia.org\/?p=14929"},"modified":"2024-11-12T09:04:01","modified_gmt":"2024-11-12T08:04:01","slug":"las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/","title":{"rendered":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones"},"content":{"rendered":"<ul>\n<li><strong>COCEMFE Castell\u00f3 ha llevado sillas de ruedas, andadores y un colch\u00f3n antiescaras a una residencia de Picanya y al centro de salud de Aldaia<\/strong><\/li>\n<li><strong>Los trabajadores de COCEMFE Alicante colaboran con Alicante Gastron\u00f3mica en la preparaci\u00f3n de comida<\/strong><\/li>\n<li><strong>COCEMFE Valencia recibe una treintena de solicitudes de ayuda y medio centenar de ofrecimientos<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Las cuatro entidades de COCEMFE en la Comunitat Valenciana, tres federaciones territoriales y la confederaci\u00f3n, se est\u00e1n volcando en la ayuda a las personas afectadas por la dana en los pueblos del sur de Valencia.<\/p>\n<p>COCEMFE Valencia ha recibido 27 solicitudes de ayuda en su servicio de mapeo de necesidades activado para atender a las personas con discapacidad afectadas por la dana. Las personas afectadas necesitan reparaciones de sillas de ruedas, tanto manuales como el\u00e9ctricas, andadores, camillas, camas articuladas y alojamiento en hogares accesibles. La forma de contacto es a trav\u00e9s del tel\u00e9fono 963 83 77 08.<\/p>\n<p>Por otro lado, la entidad ha recibido 50 ofrecimientos de ayuda de materiales como sillas de ruedas, camas, colchones, andadores, material de ayuda a la degluci\u00f3n, gr\u00faas de movilidad personal, atenci\u00f3n psicol\u00f3gica, transporte adaptado o alojamiento accesible.<\/p>\n<p>A fecha de hoy, aproximadamente la mitad de las solicitudes y los ofrecimientos han sido cruzados para dar una respuesta, aunque esta se est\u00e1 viendo entorpecida por las dificultades de acceso a la zona, seg\u00fan han explicado desde la entidad.<\/p>\n<p><strong>Ayuda desde Castell\u00f3n y Alicante<\/strong><\/p>\n<p>Por su parte, COCEMFE Castell\u00f3 estuvo ayer jueves en los pueblos del sur de Valencia para llevar dos sillas de ruedas, dos andadores y un colch\u00f3n antiescaras para la residencia Amelia Piedras Mill\u00e1n de Pica\u00f1a y tambi\u00e9n en el Centro de Salud de Aldaia para dejar dos sillas de ruedas y siete andadores. Este domingo 10 de noviembre se desplazar\u00e1n de nuevo con personas voluntarias para tareas de limpieza y con trabajadoras sociales, psic\u00f3logas y enfermeras para atender a personas con discapacidad y personas mayores.Tambi\u00e9n participar\u00e1n en el reparto de comida a personas mayores en Massanassa.<\/p>\n<p>Desde el sur, parte del personal t\u00e9cnico de COCEMFE Alicante ha formado parte del equipo de personas voluntarias de Alicante Gastron\u00f3mica Solidaria, una iniciativa que lleva 8 d\u00edas cocinando para las personas afectadas por la dana. Esta acci\u00f3n desinteresada de la federaci\u00f3n ha contribuido para que en el d\u00eda de ayer se pudieran entregar m\u00e1s de 16.000 men\u00fas. Adem\u00e1s, ha puesto a disposici\u00f3n una plaza en su residencia para personas en situaci\u00f3n de gran dependencia y su bando de ayudas t\u00e9cnicas.<\/p>\n<p><strong>Asesoramiento para la gesti\u00f3n de ayudas<\/strong><\/p>\n<p>Finalmente, COCEMFE Comunitat Valenciana ha puesto a disposici\u00f3n de las personas afectadas sus servicios de Asesoramiento Jur\u00eddico para atender dudas en la gesti\u00f3n de las ayudas articuladas por la dana, su servicio de Educaci\u00f3n Inclusiva para atender solicitudes de comunicadores y otro material educativo accesible, y su servicio de Accesibilidad.<\/p>\n<p>El presidente de la confederaci\u00f3n, Albert Mar\u00edn, ha visibilizado la necesidad de que se creen puntos f\u00edsicos accesibles para la gesti\u00f3n de las ayudas oficiales: \u201cHay que tener en cuenta la brecha digital en las personas con discapacidad y las personas mayores, as\u00ed como la dificultad de desplazamientos, por lo que consideramos especialmente \u00fatil que se establezcan varias oficinas de atenci\u00f3n personal en las zonas afectadas para facilitar a estos colectivos la tramitaci\u00f3n de estas ayudas\u201d, ha manifestado.<\/p>\n<p>Adem\u00e1s, quiere agradecer a las federaciones provinciales si implicaci\u00f3n y a todas aquellas personas que est\u00e1n colaborando a trav\u00e9s de donaciones de material y ofrecimientos de ayuda para las personas con discapacidad.<\/p>\n<p>Visitas: 145<\/p>","protected":false},"excerpt":{"rendered":"<p>COCEMFE Castell\u00f3 ha llevado sillas de ruedas, andadores y un colch\u00f3n antiescaras a una residencia de Picanya y al centro de salud de Aldaia Los trabajadores de COCEMFE Alicante colaboran con Alicante Gastron\u00f3mica en la preparaci\u00f3n de comida COCEMFE Valencia recibe una treintena de solicitudes de ayuda y medio centenar de ofrecimientos &nbsp; Las cuatro&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":14930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[123],"tags":[140,598,200,596,148],"class_list":["post-14929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-val","tag-accesibilidad-val","tag-ayuda-dana","tag-cocemfe-val","tag-dana-valencia","tag-discapacidad-val"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"COCEMFE Castell\u00f3 ha llevado sillas de ruedas, andadores y un colch\u00f3n antiescaras a una residencia de Picanya y al centro de salud de Aldaia Los trabajadores de COCEMFE Alicante colaboran con Alicante Gastron\u00f3mica en la preparaci\u00f3n de comida COCEMFE Valencia recibe una treintena de solicitudes de ayuda y medio centenar de ofrecimientos &nbsp; Las cuatro&hellip;&nbsp;Leer m\u00e1s &raquo;Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T12:02:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T08:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicacio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicacio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/\"},\"author\":{\"name\":\"comunicacio\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/84dc42180efe17bdafa0a7a8702d24c8\"},\"headline\":\"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones\",\"datePublished\":\"2024-11-08T12:02:09+00:00\",\"dateModified\":\"2024-11-12T08:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/\"},\"wordCount\":634,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg\",\"keywords\":[\"accesibilidad\",\"ayuda dana\",\"COCEMFE\",\"dana valencia\",\"discapacidad\"],\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/\",\"name\":\"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg\",\"datePublished\":\"2024-11-08T12:02:09+00:00\",\"dateModified\":\"2024-11-12T08:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg\",\"width\":1706,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/84dc42180efe17bdafa0a7a8702d24c8\",\"name\":\"comunicacio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g\",\"caption\":\"comunicacio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/","og_locale":"es_ES","og_type":"article","og_title":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia","og_description":"COCEMFE Castell\u00f3 ha llevado sillas de ruedas, andadores y un colch\u00f3n antiescaras a una residencia de Picanya y al centro de salud de Aldaia Los trabajadores de COCEMFE Alicante colaboran con Alicante Gastron\u00f3mica en la preparaci\u00f3n de comida COCEMFE Valencia recibe una treintena de solicitudes de ayuda y medio centenar de ofrecimientos &nbsp; Las cuatro&hellip;&nbsp;Leer m\u00e1s &raquo;Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones","og_url":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2024-11-08T12:02:09+00:00","article_modified_time":"2024-11-12T08:04:01+00:00","og_image":[{"width":1706,"height":2560,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg","type":"image\/jpeg"}],"author":"comunicacio","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"comunicacio","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/"},"author":{"name":"comunicacio","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/84dc42180efe17bdafa0a7a8702d24c8"},"headline":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones","datePublished":"2024-11-08T12:02:09+00:00","dateModified":"2024-11-12T08:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/"},"wordCount":634,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg","keywords":["accesibilidad","ayuda dana","COCEMFE","dana valencia","discapacidad"],"articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/","url":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/","name":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg","datePublished":"2024-11-08T12:02:09+00:00","dateModified":"2024-11-12T08:04:01+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2024\/11\/COCEMFE-ALICANTE_ALICANTE-GASTRONOMICA-scaled.jpg","width":1706,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/las-entidades-de-cocemfe-en-la-comunitat-valenciana-preparan-comida-y-donan-sillas-de-ruedas-andadores-y-colchones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las entidades de COCEMFE en la Comunitat Valenciana preparan comida y donan sillas de ruedas, andadores y colchones"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/84dc42180efe17bdafa0a7a8702d24c8","name":"comunicacio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc921e89975f546bc4139f170e59e0d573a099452a8a989eb18e18cda2e7227a?s=96&d=mm&r=g","caption":"comunicacio"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/14929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=14929"}],"version-history":[{"count":1,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/14929\/revisions"}],"predecessor-version":[{"id":14932,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/14929\/revisions\/14932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/14930"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=14929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=14929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=14929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}