{"id":2689,"date":"2019-02-14T18:00:56","date_gmt":"2019-02-14T16:00:56","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=2689"},"modified":"2019-02-14T18:00:56","modified_gmt":"2019-02-14T16:00:56","slug":"alumnes-del-ies-visiten-cocemfe-valencia","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/","title":{"rendered":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2689\" class=\"elementor elementor-2689 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3340753 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3340753\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8585d22\" data-id=\"8585d22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e635efe elementor-widget elementor-widget-image\" data-id=\"e635efe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-1024x576.jpg\" class=\"attachment-large size-large wp-image-2690\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-1024x576.jpg 1024w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-300x169.jpg 300w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-768x432.jpg 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-1536x864.jpg 1536w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b40ae2\" data-id=\"2b40ae2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88dc4df elementor-widget elementor-widget-text-editor\" data-id=\"88dc4df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ahir 13 de Febrer , van visitar les nostres instal\u00b7lacions m\u00e9s d&#8217;una vintena d&#8217;alumnes del Cicle Superior d&#8217;Integraci\u00f3 Social de l&#8217;IES Tierno Galv\u00e1n de Moncada.<\/p><p>En\u00a0 COCEMFE Val\u00e8ncia, van poder vore les instal\u00b7lacions fent insist\u00e8ncia en l&#8217;accessibilitat del nostre local, a m\u00e9s de presentar-los a algunes persones amb discapacitat perqu\u00e8 conegueren patologies com la fibromialgia, Ictus, poliomielitis, i Esclerosi m\u00faltiple.<\/p><p>D&#8217;altra banda, van rebre una\u00a0 xarrada formativa a c\u00e0rrec de M\u00aa Jos\u00e9 Carre\u00f1o i Estela Ruiz, ambd\u00f3s t\u00e8cnics de la nostra entitat, on es van explicar els serveis que du a terme la nostra Federaci\u00f3.<\/p><p>A m\u00e9s, comptem amb l&#8217;experi\u00e8ncia en primera persona de Paula Lara, usu\u00e0ria del Servici d&#8217;Integraci\u00f3 laboral, i amb Juan Benajes, usuari del programa de Foment d&#8217;autonomia personal que van comentar la seua experi\u00e8ncia\u00a0 com a persones amb discapacitat, qu\u00e9 recursos havien sigut facilitats des de COCEMFE Val\u00e8ncia.<\/p><p>Juan Benajes, va parlar del moviment de vida independent i de la figura de l&#8217;Assistent personal i Paula Lara va destacar el suport del personal t\u00e8cnic de l&#8217;entitat en les accions de busca d&#8217;ocupaci\u00f3.<\/p><p>Amb este tipus d&#8217;iniciatives, els futurs professionals poden coneixer la nostra entitat, aix\u00ed com tindre una visi\u00f3 m\u00e9s \u00e0mplia de diferents tipus de discapacitats.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<p>Visitas: 7<\/p>","protected":false},"excerpt":{"rendered":"<p>Ahir 13 de Febrer , van visitar les nostres instal\u00b7lacions m\u00e9s d&#8217;una vintena d&#8217;alumnes del Cicle Superior d&#8217;Integraci\u00f3 Social de l&#8217;IES Tierno Galv\u00e1n de Moncada. En\u00a0 COCEMFE Val\u00e8ncia, van poder vore les instal\u00b7lacions fent insist\u00e8ncia en l&#8217;accessibilitat del nostre local, a m\u00e9s de presentar-los a algunes persones amb discapacitat perqu\u00e8 conegueren patologies com la fibromialgia,&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":2690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-2689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"Ahir 13 de Febrer , van visitar les nostres instal\u00b7lacions m\u00e9s d&#8217;una vintena d&#8217;alumnes del Cicle Superior d&#8217;Integraci\u00f3 Social de l&#8217;IES Tierno Galv\u00e1n de Moncada. En\u00a0 COCEMFE Val\u00e8ncia, van poder vore les instal\u00b7lacions fent insist\u00e8ncia en l&#8217;accessibilitat del nostre local, a m\u00e9s de presentar-los a algunes persones amb discapacitat perqu\u00e8 conegueren patologies com la fibromialgia,&hellip;&nbsp;Leer m\u00e1s &raquo;Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-14T16:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia\",\"datePublished\":\"2019-02-14T16:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/\"},\"wordCount\":230,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/fotos-noticia.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/\",\"name\":\"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/fotos-noticia.jpg\",\"datePublished\":\"2019-02-14T16:00:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/fotos-noticia.jpg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/fotos-noticia.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/alumnes-del-ies-visiten-cocemfe-valencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/","og_locale":"es_ES","og_type":"article","og_title":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia","og_description":"Ahir 13 de Febrer , van visitar les nostres instal\u00b7lacions m\u00e9s d&#8217;una vintena d&#8217;alumnes del Cicle Superior d&#8217;Integraci\u00f3 Social de l&#8217;IES Tierno Galv\u00e1n de Moncada. En\u00a0 COCEMFE Val\u00e8ncia, van poder vore les instal\u00b7lacions fent insist\u00e8ncia en l&#8217;accessibilitat del nostre local, a m\u00e9s de presentar-los a algunes persones amb discapacitat perqu\u00e8 conegueren patologies com la fibromialgia,&hellip;&nbsp;Leer m\u00e1s &raquo;Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia","og_url":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2019-02-14T16:00:56+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg","type":"image\/jpeg"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia","datePublished":"2019-02-14T16:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/"},"wordCount":230,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/","url":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/","name":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg","datePublished":"2019-02-14T16:00:56+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/02\/fotos-noticia.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/alumnes-del-ies-visiten-cocemfe-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"Alumnes del IES Enrique Tierno Galv\u00e1n de Moncada visiten COCEMFE Val\u00e8ncia"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/2689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=2689"}],"version-history":[{"count":0,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/2689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/2690"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=2689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=2689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=2689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}