{"id":2749,"date":"2019-03-04T15:18:44","date_gmt":"2019-03-04T13:18:44","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=2749"},"modified":"2019-03-04T15:18:44","modified_gmt":"2019-03-04T13:18:44","slug":"cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/","title":{"rendered":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2749\" class=\"elementor elementor-2749 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67061fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67061fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b136c00\" data-id=\"b136c00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-051d4ea elementor-widget elementor-widget-image\" data-id=\"051d4ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"971\" height=\"1024\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-971x1024.jpg\" class=\"attachment-large size-large wp-image-2751\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-971x1024.jpg 971w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-284x300.jpg 284w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-768x810.jpg 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-1456x1536.jpg 1456w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-1941x2048.jpg 1941w\" sizes=\"(max-width: 971px) 100vw, 971px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31cb9c1\" data-id=\"31cb9c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af2778f elementor-widget elementor-widget-text-editor\" data-id=\"af2778f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>COCEMFE Val\u00e8ncia ha desenvolupat durant el 2018 i 2019 el projecte Foment de l&#8217;autonomia personal per a 41 persones amb diversitat funcional (discapacitat f\u00edsica i\/o org\u00e0nica) , oferint-los la possibilitat de realitzar de forma independent aquelles activitats per a les que requeria d&#8217;ajuda de tercera persona, amb l&#8217;objectiu de millorar la qualitat de vida, l&#8217;autonomia personal i la inclusi\u00f3 social i poder afavorir aix\u00ed la perman\u00e8ncia en l&#8217;entorn en qu\u00e8 desenvolupen la seua vida.<\/p><p>Este projecte s&#8217;ha executat gr\u00e0cies a la subvenci\u00f3 de 11.567 euros procedent de la Convocat\u00f2ria de Subvencions per a la realitzaci\u00f3 de projectes d&#8217;Intervenci\u00f3 en l&#8217;\u00c0mbit de l&#8217;Acci\u00f3 Social de l&#8217;Ajuntament de Val\u00e8ncia, entre altres que rep COCEMFE Val\u00e8ncia.<\/p><p>En este projecte s&#8217;ha prestat un conjunt de servicis especialitzats, que han at\u00e9s professionalment i des d&#8217;una perspectiva integral, a persones amb diversitat funcional (discapacitat f\u00edsica i\/o org\u00e0nica) en situaci\u00f3 de depend\u00e8ncia, sempre dins de l&#8217;entorn propi i amb intervencions comunit\u00e0ries que han potenciat el desenvolupament d&#8217;una vida aut\u00f2noma, partint de l&#8217;establiment del benestar bio-psico- social de la persona.<\/p><p>Servicis especialitzats com ara servicis de suport en la rehabilitaci\u00f3, servicis d&#8217;informaci\u00f3, orientaci\u00f3 i suport en la busca de recursos, servicis d&#8217;acompanyament, servicis d&#8217;informaci\u00f3 i suport per a la utilitzaci\u00f3 aut\u00f2noma de mitjans de transport p\u00fablic adaptats, servicis d&#8217;aprenentatge de l&#8217;\u00fas de sistemes de comunicaci\u00f3 alternatius i servicis de suport en activitats d&#8217;atenci\u00f3 personal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-560b20f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"560b20f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81dd80c\" data-id=\"81dd80c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-babca2d elementor-widget elementor-widget-image\" data-id=\"babca2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2018\/09\/LOGO-AYUNTAMIENTO-300x100.png\" class=\"attachment-medium size-medium wp-image-1808\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2018\/09\/LOGO-AYUNTAMIENTO-300x100.png 300w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2018\/09\/LOGO-AYUNTAMIENTO-768x255.png 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2018\/09\/LOGO-AYUNTAMIENTO.png 1016w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<p>Visitas: 2<\/p>","protected":false},"excerpt":{"rendered":"<p>COCEMFE Val\u00e8ncia ha desenvolupat durant el 2018 i 2019 el projecte Foment de l&#8217;autonomia personal per a 41 persones amb diversitat funcional (discapacitat f\u00edsica i\/o org\u00e0nica) , oferint-los la possibilitat de realitzar de forma independent aquelles activitats per a les que requeria d&#8217;ajuda de tercera persona, amb l&#8217;objectiu de millorar la qualitat de vida, l&#8217;autonomia&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":2751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-2749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#039;autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#039;autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"COCEMFE Val\u00e8ncia ha desenvolupat durant el 2018 i 2019 el projecte Foment de l&#8217;autonomia personal per a 41 persones amb diversitat funcional (discapacitat f\u00edsica i\/o org\u00e0nica) , oferint-los la possibilitat de realitzar de forma independent aquelles activitats per a les que requeria d&#8217;ajuda de tercera persona, amb l&#8217;objectiu de millorar la qualitat de vida, l&#8217;autonomia&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-04T13:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2426\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional\",\"datePublished\":\"2019-03-04T13:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/\"},\"wordCount\":258,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/DSC00943-scaled.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/\",\"name\":\"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l'autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/DSC00943-scaled.jpg\",\"datePublished\":\"2019-03-04T13:18:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/DSC00943-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/DSC00943-scaled.jpg\",\"width\":2426,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l'autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/","og_locale":"es_ES","og_type":"article","og_title":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l'autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia","og_description":"COCEMFE Val\u00e8ncia ha desenvolupat durant el 2018 i 2019 el projecte Foment de l&#8217;autonomia personal per a 41 persones amb diversitat funcional (discapacitat f\u00edsica i\/o org\u00e0nica) , oferint-los la possibilitat de realitzar de forma independent aquelles activitats per a les que requeria d&#8217;ajuda de tercera persona, amb l&#8217;objectiu de millorar la qualitat de vida, l&#8217;autonomia&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional","og_url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2019-03-04T13:18:44+00:00","og_image":[{"width":2426,"height":2560,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg","type":"image\/jpeg"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional","datePublished":"2019-03-04T13:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/"},"wordCount":258,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/","url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/","name":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l'autonomia personal per a persones amb diversitat funcional - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg","datePublished":"2019-03-04T13:18:44+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2019\/03\/DSC00943-scaled.jpg","width":2426,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-projecte-foment-de-lautonomia-personal-per-a-persones-amb-diversitat-funcional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"COCEMFE Val\u00e8ncia ha desenvolupat el Projecte Foment de l&#8217;autonomia personal per a persones amb diversitat funcional"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/2749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=2749"}],"version-history":[{"count":0,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/2749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/2751"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=2749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=2749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}