{"id":5088,"date":"2021-04-23T10:57:47","date_gmt":"2021-04-23T08:57:47","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=5088"},"modified":"2024-04-11T17:11:38","modified_gmt":"2024-04-11T15:11:38","slug":"cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/","title":{"rendered":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5088\" class=\"elementor elementor-5088\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d022b97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d022b97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43c40d3\" data-id=\"43c40d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89a4a0d elementor-widget elementor-widget-image\" data-id=\"89a4a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-5091\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-1024x768.jpg 1024w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-300x225.jpg 300w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-768x576.jpg 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-1536x1152.jpg 1536w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_134005-min-scaled-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7ae166\" data-id=\"a7ae166\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45f7b2d elementor-widget elementor-widget-image\" data-id=\"45f7b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-5090\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-1024x768.jpg 1024w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-300x225.jpg 300w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-768x576.jpg 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-1536x1152.jpg 1536w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46fde7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46fde7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0329279\" data-id=\"0329279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d38319 elementor-widget elementor-widget-text-editor\" data-id=\"8d38319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el marco de este convenio COCEMFE Val\u00e8ncia, ha incorporado en su p\u00e1gina web, el sistema de accesibilidad web inSuit, facilitando con sus diversas herramientas, seg\u00fan la necesidades de cada persona, el acceso a la informaci\u00f3n de inter\u00e9s para las personas con discapacidad y sus familias. As\u00ed como, otras informaciones como las convocatorias de ayudas de las administraciones p\u00fablicas o privadas, informaci\u00f3n de nuestra bolsa de empleo y actividades de formaci\u00f3n, de Accesibilidad, Sanidad, y Contra la brecha digital.<\/p><p>En el acto el presidente de la Federaci\u00f3n Pascual Castell\u00f3 y el director de la empresa Daas Group Juan Antonio Cebollada, constataron como principales objetivos \u201cel fomentar la difusi\u00f3n entre las administraciones publicas de las leyes de accesibilidad que obligan a cumplir con los est\u00e1ndares y normativas de la accesibilidad web, tal como recoge el Real Decreto 1112\/2018 que culmin\u00f3 su moratoria el pasado 20 de septiembre de 2020. As\u00ed como dar a conocer la problem\u00e1tica de la accesibilidad web e impulsar la adopci\u00f3n de herramientas de accesibilidad como inSuit para garantizar el acceso a los contenidos y servicios de la web, a personas con discapacidad, adultos mayores, y personas con falta de conocimientos tecnol\u00f3gicos, o diferentes problemas para navegar en la web.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edf740a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edf740a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d6d249\" data-id=\"3d6d249\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9968870 elementor-widget elementor-widget-image\" data-id=\"9968870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-5092\" alt=\"\" srcset=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-1024x768.jpg 1024w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-300x225.jpg 300w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-768x576.jpg 768w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-1536x1152.jpg 1536w, https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_133849-1-min-scaled-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2072c1e\" data-id=\"2072c1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12b7fb5 elementor-widget elementor-widget-text-editor\" data-id=\"12b7fb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con este convenio la Federaci\u00f3n COCEMFE Val\u00e8ncia se suma al \u201cClub de Entidades e instituciones amigas de la \u201cAccesibilidad Web\u201d junto a COCEMFE CV y COCEMFE Alicante, que disponen del sistema inSuit en sus cuatro p\u00e1ginas web.<\/p><p>InSuit es una herramienta que permite a la persona usuaria navegar con interfaces adaptadas a sus necesidades, desde cualquier ordenador y de manera gratuita para el usuario, eligiendo diferentes maneras de navegaci\u00f3n sin la necesidad de perif\u00e9ricos ni hardware adicional. Estas maneras de navegaci\u00f3n son con teclado, por comandos de voz, con sonidos, con pulsador o con comunicaci\u00f3n aumentada. Tambi\u00e9n dispone de un lector de pantalla en la nube y es compatible con lectores de pantalla. Esta ayuda est\u00e1 destinada a todo tipo de discapacidad f\u00edsica, sensorial o auditiva: disminuci\u00f3n o falta de visi\u00f3n, daltonismo, dificultad o falta de movilidad en manos y brazos, con dificultades para el habla, discapacidad cognitiva o dislexia. InSuit tambi\u00e9n hace m\u00e1s sencillo navegar para personas mayores o con pocas capacidades digitales.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<p>Visitas: 10<\/p>","protected":false},"excerpt":{"rendered":"<p>En el marco de este convenio COCEMFE Val\u00e8ncia, ha incorporado en su p\u00e1gina web, el sistema de accesibilidad web inSuit, facilitando con sus diversas herramientas, seg\u00fan la necesidades de cada persona, el acceso a la informaci\u00f3n de inter\u00e9s para las personas con discapacidad y sus familias. As\u00ed como, otras informaciones como las convocatorias de ayudas&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":5090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-5088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"En el marco de este convenio COCEMFE Val\u00e8ncia, ha incorporado en su p\u00e1gina web, el sistema de accesibilidad web inSuit, facilitando con sus diversas herramientas, seg\u00fan la necesidades de cada persona, el acceso a la informaci\u00f3n de inter\u00e9s para las personas con discapacidad y sus familias. As\u00ed como, otras informaciones como las convocatorias de ayudas&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-23T08:57:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T15:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit\",\"datePublished\":\"2021-04-23T08:57:47+00:00\",\"dateModified\":\"2024-04-11T15:11:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/20210421_131919-1-min-scaled-1.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/\",\"name\":\"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/20210421_131919-1-min-scaled-1.jpg\",\"datePublished\":\"2021-04-23T08:57:47+00:00\",\"dateModified\":\"2024-04-11T15:11:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/20210421_131919-1-min-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/20210421_131919-1-min-scaled-1.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/","og_locale":"es_ES","og_type":"article","og_title":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia","og_description":"En el marco de este convenio COCEMFE Val\u00e8ncia, ha incorporado en su p\u00e1gina web, el sistema de accesibilidad web inSuit, facilitando con sus diversas herramientas, seg\u00fan la necesidades de cada persona, el acceso a la informaci\u00f3n de inter\u00e9s para las personas con discapacidad y sus familias. As\u00ed como, otras informaciones como las convocatorias de ayudas&hellip;&nbsp;Leer m\u00e1s &raquo;COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit","og_url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2021-04-23T08:57:47+00:00","article_modified_time":"2024-04-11T15:11:38+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg","type":"image\/jpeg"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit","datePublished":"2021-04-23T08:57:47+00:00","dateModified":"2024-04-11T15:11:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/"},"wordCount":422,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/","url":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/","name":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg","datePublished":"2021-04-23T08:57:47+00:00","dateModified":"2024-04-11T15:11:38+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2021\/04\/20210421_131919-1-min-scaled-1.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/cocemfe-valencia-signa-un-conveni-de-col%c2%b7laboracio-amb-daas-group-empresa-valenciana-guardonada-amb-el-premi-reina-letizia-de-tecnologies-daccessibilitat-pel-seu-programa-daccessibilitat-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"COCEMFE Val\u00e8ncia firma un Convenio de colaboraci\u00f3n con Daas Group empresa Valenciana galardonada con el premio Reina Letizia de Tecnolog\u00edas de Accesibilidad por su programa de accesibilidad Web inSuit"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/5088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=5088"}],"version-history":[{"count":8,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/5088\/revisions"}],"predecessor-version":[{"id":13993,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/5088\/revisions\/13993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/5090"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=5088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=5088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=5088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}