{"id":6836,"date":"2023-04-25T10:17:52","date_gmt":"2023-04-25T08:17:52","guid":{"rendered":"http:\/\/cocemfevalencia.org\/?p=6836"},"modified":"2023-07-10T08:44:48","modified_gmt":"2023-07-10T06:44:48","slug":"el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas","status":"publish","type":"post","link":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/","title":{"rendered":"El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-11526 size-medium\" src=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/Descobrim_2023_Taller_2-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" \/>La tercera edici\u00f3n del Cicle Cultural &#8216;<strong>Descobrim&#8217;<\/strong>, la muestra art\u00edstica de <strong>COCEMFE Valencia<\/strong> en colaboraci\u00f3n con <strong>Caixa Popular<\/strong>, propone a las personas asociadas a las diferentes entidades integradas en la federaci\u00f3n el taller de teatro &#8216;Coratge&#8217;. Los y las participantes de esta actividad dividida en diez sesiones entre los meses de mayo y junio, podr\u00e1n iniciarse en la disciplina art\u00edstica del teatro de la mano de dos figuras profesionales del sector: <a href=\"https:\/\/drive.google.com\/file\/d\/13XjjJnhZe6t2KGi034qKPnYrg6o-hFle\/view?usp=sharing\">Ana Campos del Alc\u00e1zar<\/a> y <a href=\"https:\/\/drive.google.com\/file\/d\/1-Z8H6-1MlU62PUTQ6bIJYf1l5iWcoy8_\/view?usp=share_link\">Domingo Chinchilla<\/a>, ambas con una dilata carrera en las artes vivas.<\/p>\n<p>El precio total del taller ser\u00e1 de <strong>80\u20ac<\/strong> y se llevar\u00e1 a cabo en el <strong>Teatro C\u00edrculo <\/strong>(Calle Prudenci Alc\u00f3n i Mateu 3, bajo izq. 46020 \u2013 Val\u00e8ncia,\u00a0Barri de Benimaclet)<\/p>\n<p><strong>Fechas:<\/strong><\/p>\n<p>Lunes: 8, 15 y 22 de mayo y 5 de junio (11:00h a 13:00h)<\/p>\n<p>Martes: 9 y 16 de mayo (17:00 a 19:00 horas)<\/p>\n<p>Jueves y viernes: 8 y 9 de junio (17:00h a 20:00h)<\/p>\n<p>Domingo: 11 de junio, representaci\u00f3n escena Cicle Cultural &#8216;Descobrim&#8217; (19:00h)<\/p>\n<p>Si tienes cualquier duda o quieres apuntarte, \u00a1no lo dudes!<\/p>\n<ul>\n<li>Escribe un whatsapp al\u00a034 608 16 98 33<\/li>\n<li>Env\u00eda un correo a activitats@cocemfevalencia.org<\/li>\n<\/ul>\n<p>Visitas: 21<\/p>","protected":false},"excerpt":{"rendered":"<p>La tercera edici\u00f3n del Cicle Cultural &#8216;Descobrim&#8217;, la muestra art\u00edstica de COCEMFE Valencia en colaboraci\u00f3n con Caixa Popular, propone a las personas asociadas a las diferentes entidades integradas en la federaci\u00f3n el taller de teatro &#8216;Coratge&#8217;. Los y las participantes de esta actividad dividida en diez sesiones entre los meses de mayo y junio, podr\u00e1n&hellip;&nbsp;<a href=\"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":10462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[253,5],"tags":[274],"class_list":["post-6836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cicle-cultural-descobrim","category-noticias","tag-cicel-cultural-descobrim"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Cicle Cultural &#039;Descobrim&#039; lanza un taller de teatro para personas asociadas - Cocemfe Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Cicle Cultural &#039;Descobrim&#039; lanza un taller de teatro para personas asociadas - Cocemfe Valencia\" \/>\n<meta property=\"og:description\" content=\"La tercera edici\u00f3n del Cicle Cultural &#8216;Descobrim&#8217;, la muestra art\u00edstica de COCEMFE Valencia en colaboraci\u00f3n con Caixa Popular, propone a las personas asociadas a las diferentes entidades integradas en la federaci\u00f3n el taller de teatro &#8216;Coratge&#8217;. Los y las participantes de esta actividad dividida en diez sesiones entre los meses de mayo y junio, podr\u00e1n&hellip;&nbsp;Leer m\u00e1s &raquo;El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocemfe Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cocemfe.valencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-25T08:17:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T06:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1334\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"COCEMFE VALENCIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:site\" content=\"@COCEMFEValencia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"COCEMFE VALENCIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/\"},\"author\":{\"name\":\"COCEMFE VALENCIA\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\"},\"headline\":\"El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas\",\"datePublished\":\"2023-04-25T08:17:52+00:00\",\"dateModified\":\"2023-07-10T06:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/\"},\"wordCount\":194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DESCOBRIM_2023_CORATGE.png\",\"keywords\":[\"Cicel Cultural 'Descobrim'\"],\"articleSection\":[\"Cicle Cultural DESCOBRIM\",\"Not\u00edcies\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/\",\"name\":\"El Cicle Cultural 'Descobrim' lanza un taller de teatro para personas asociadas - Cocemfe Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DESCOBRIM_2023_CORATGE.png\",\"datePublished\":\"2023-04-25T08:17:52+00:00\",\"dateModified\":\"2023-07-10T06:44:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DESCOBRIM_2023_CORATGE.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DESCOBRIM_2023_CORATGE.png\",\"width\":1334,\"height\":2000,\"caption\":\"III CICLE CULTURAL DESCOBRIM. MAIG-JUNY 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"name\":\"Cocemfe Valencia\",\"description\":\"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#organization\",\"name\":\"Cocemfe Valencia\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"contentUrl\":\"https:\\\/\\\/cocemfevalencia.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png\",\"width\":2334,\"height\":613,\"caption\":\"Cocemfe Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cocemfe.valencia\",\"https:\\\/\\\/x.com\\\/COCEMFEValencia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cocemfevalencia.org\\\/es\\\/#\\\/schema\\\/person\\\/e31a24227ccbc918e2c80add51990ad7\",\"name\":\"COCEMFE VALENCIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g\",\"caption\":\"COCEMFE VALENCIA\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Cicle Cultural 'Descobrim' lanza un taller de teatro para personas asociadas - Cocemfe Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/","og_locale":"es_ES","og_type":"article","og_title":"El Cicle Cultural 'Descobrim' lanza un taller de teatro para personas asociadas - Cocemfe Valencia","og_description":"La tercera edici\u00f3n del Cicle Cultural &#8216;Descobrim&#8217;, la muestra art\u00edstica de COCEMFE Valencia en colaboraci\u00f3n con Caixa Popular, propone a las personas asociadas a las diferentes entidades integradas en la federaci\u00f3n el taller de teatro &#8216;Coratge&#8217;. Los y las participantes de esta actividad dividida en diez sesiones entre los meses de mayo y junio, podr\u00e1n&hellip;&nbsp;Leer m\u00e1s &raquo;El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas","og_url":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/","og_site_name":"Cocemfe Valencia","article_publisher":"https:\/\/www.facebook.com\/cocemfe.valencia","article_published_time":"2023-04-25T08:17:52+00:00","article_modified_time":"2023-07-10T06:44:48+00:00","og_image":[{"width":1334,"height":2000,"url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png","type":"image\/png"}],"author":"COCEMFE VALENCIA","twitter_card":"summary_large_image","twitter_creator":"@COCEMFEValencia","twitter_site":"@COCEMFEValencia","twitter_misc":{"Escrito por":"COCEMFE VALENCIA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#article","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/"},"author":{"name":"COCEMFE VALENCIA","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7"},"headline":"El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas","datePublished":"2023-04-25T08:17:52+00:00","dateModified":"2023-07-10T06:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/"},"wordCount":194,"commentCount":0,"publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png","keywords":["Cicel Cultural 'Descobrim'"],"articleSection":["Cicle Cultural DESCOBRIM","Not\u00edcies"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/","url":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/","name":"El Cicle Cultural 'Descobrim' lanza un taller de teatro para personas asociadas - Cocemfe Valencia","isPartOf":{"@id":"https:\/\/cocemfevalencia.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#primaryimage"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#primaryimage"},"thumbnailUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png","datePublished":"2023-04-25T08:17:52+00:00","dateModified":"2023-07-10T06:44:48+00:00","breadcrumb":{"@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#primaryimage","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/04\/DESCOBRIM_2023_CORATGE.png","width":1334,"height":2000,"caption":"III CICLE CULTURAL DESCOBRIM. MAIG-JUNY 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/cocemfevalencia.org\/es\/el-cicle-cultural-descobrim-lanza-un-taller-de-teatro-para-personas-asociadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cocemfevalencia.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Cicle Cultural &#8216;Descobrim&#8217; lanza un taller de teatro para personas asociadas"}]},{"@type":"WebSite","@id":"https:\/\/cocemfevalencia.org\/es\/#website","url":"https:\/\/cocemfevalencia.org\/es\/","name":"Cocemfe Valencia","description":"FEDERACI\u00d3N DE ASOCIACIONES DE PERSONAS CON DISCAPACIDAD F\u00cdSICA Y ORG\u00c1NICA DE LA PROV\u00cdNCIA DE VALENCIA","publisher":{"@id":"https:\/\/cocemfevalencia.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocemfevalencia.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cocemfevalencia.org\/es\/#organization","name":"Cocemfe Valencia","url":"https:\/\/cocemfevalencia.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","contentUrl":"https:\/\/cocemfevalencia.org\/wp-content\/uploads\/2023\/03\/0312-Horizontal-una-linea-larga-rgb-positivo-Tricolor.png","width":2334,"height":613,"caption":"Cocemfe Valencia"},"image":{"@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cocemfe.valencia","https:\/\/x.com\/COCEMFEValencia"]},{"@type":"Person","@id":"https:\/\/cocemfevalencia.org\/es\/#\/schema\/person\/e31a24227ccbc918e2c80add51990ad7","name":"COCEMFE VALENCIA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81dd2ced4591577d70433bbfde65ba3f931e09f5cb4ca8c890817c47789b47f0?s=96&d=mm&r=g","caption":"COCEMFE VALENCIA"}}]}},"_links":{"self":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/6836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/comments?post=6836"}],"version-history":[{"count":1,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/6836\/revisions"}],"predecessor-version":[{"id":11651,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/posts\/6836\/revisions\/11651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media\/10462"}],"wp:attachment":[{"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/media?parent=6836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/categories?post=6836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocemfevalencia.org\/es\/wp-json\/wp\/v2\/tags?post=6836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}